{"id":2372,"date":"2021-11-28T21:03:02","date_gmt":"2021-11-28T20:03:02","guid":{"rendered":"https:\/\/muchenberger.ch\/produkt\/aquabrome\/"},"modified":"2021-11-28T21:03:02","modified_gmt":"2021-11-28T20:03:02","slug":"aquabrome-2","status":"publish","type":"product","link":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/","title":{"rendered":"Aquabrome"},"content":{"rendered":"<p class=\"p1\">Water disinfection with the chemical substance bromine.<\/p>\n<p>Bucket of 5 kg.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Water disinfection bromine<\/p>\n","protected":false},"featured_media":1961,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[110,111,119],"product_tag":[],"class_list":["post-2372","product","type-product","status-publish","has-post-thumbnail","product_cat-all","product_cat-bayrol_","product_cat-water-disinfection-with-bromine","product_shipping_class-domestic-package-up-to-10kg","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Aquabrome - Muchenberger AG<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Aquabrome - Muchenberger AG\" \/>\r\n<meta property=\"og:description\" content=\"Water disinfection bromine\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Muchenberger AG\" \/>\r\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/MuchenbergerBottmingen\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/\",\"name\":\"Aquabrome - Muchenberger AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg\",\"datePublished\":\"2021-11-28T20:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Bayrol Aquabrome Eimer 5kg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aquabrome-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aquabrome\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/\",\"name\":\"Muchenberger AG\",\"description\":\"Sanit&auml;r Heizung Traumbad Pool\",\"publisher\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#organization\",\"name\":\"Muchenberger AG\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/logo_muchenberger.png\",\"contentUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/logo_muchenberger.png\",\"width\":372,\"height\":134,\"caption\":\"Muchenberger AG\"},\"image\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/MuchenbergerBottmingen\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquabrome - Muchenberger AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/","og_locale":"en_US","og_type":"article","og_title":"Aquabrome - Muchenberger AG","og_description":"Water disinfection bromine","og_url":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/","og_site_name":"Muchenberger AG","article_publisher":"http:\/\/facebook.com\/MuchenbergerBottmingen","og_image":[{"width":2560,"height":2560,"url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/","url":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/","name":"Aquabrome - Muchenberger AG","isPartOf":{"@id":"https:\/\/muchenberger.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/#primaryimage"},"image":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/#primaryimage"},"thumbnailUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg","datePublished":"2021-11-28T20:03:02+00:00","breadcrumb":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/#primaryimage","url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg","contentUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/2139338-12101008-Aquabrome_5kg_23000_q-scaled.jpg","width":2560,"height":2560,"caption":"Bayrol Aquabrome Eimer 5kg"},{"@type":"BreadcrumbList","@id":"https:\/\/muchenberger.ch\/en\/produkt\/aquabrome-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/muchenberger.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/muchenberger.ch\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Aquabrome"}]},{"@type":"WebSite","@id":"https:\/\/muchenberger.ch\/en\/#website","url":"https:\/\/muchenberger.ch\/en\/","name":"Muchenberger AG","description":"Sanit&auml;r Heizung Traumbad Pool","publisher":{"@id":"https:\/\/muchenberger.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muchenberger.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/muchenberger.ch\/en\/#organization","name":"Muchenberger AG","url":"https:\/\/muchenberger.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/muchenberger.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2017\/11\/logo_muchenberger.png","contentUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2017\/11\/logo_muchenberger.png","width":372,"height":134,"caption":"Muchenberger AG"},"image":{"@id":"https:\/\/muchenberger.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/MuchenbergerBottmingen"]}]}},"_links":{"self":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product\/2372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/comments?post=2372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/media\/1961"}],"wp:attachment":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/media?parent=2372"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_brand?post=2372"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_cat?post=2372"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_tag?post=2372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}