{"id":2334,"date":"2021-11-28T23:32:31","date_gmt":"2021-11-28T22:32:31","guid":{"rendered":"https:\/\/muchenberger.ch\/produkt\/stainless-steel-cleaner-special\/"},"modified":"2021-11-28T23:32:31","modified_gmt":"2021-11-28T22:32:31","slug":"stainless-steel-cleaner-special","status":"publish","type":"product","link":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/","title":{"rendered":"Stainless steel cleaner special"},"content":{"rendered":"<p class=\"p1\">Acidic special cleaner for cleaning stainless steel parts in case of dirt, lack of shine or flash rust. Cleans, nourishes and brings back the missing shine.<\/p>\n<p><strong>Hazard statements:  <\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-1609\" src=\"https:\/\/muchenberger.ch\/wp-content\/uploads\/2022\/04\/Screenshot-2022-04-21-132346-150x150.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/muchenberger.ch\/wp-content\/uploads\/2022\/04\/Screenshot-2022-04-21-132346-150x150.png 150w, https:\/\/muchenberger.ch\/wp-content\/uploads\/2022\/04\/Screenshot-2022-04-21-132346-36x36.png 36w, https:\/\/muchenberger.ch\/wp-content\/uploads\/2022\/04\/Screenshot-2022-04-21-132346-180x180.png 180w, https:\/\/muchenberger.ch\/wp-content\/uploads\/2022\/04\/Screenshot-2022-04-21-132346-100x100.png 100w, https:\/\/muchenberger.ch\/wp-content\/uploads\/2022\/04\/Screenshot-2022-04-21-132346-300x300.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Acidic stainless steel cleaner<\/p>\n","protected":false},"featured_media":3217,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[110,111,114,117],"product_tag":[],"class_list":["post-2334","product","type-product","status-publish","has-post-thumbnail","product_cat-all","product_cat-bayrol_","product_cat-cleaning","product_cat-special-cleaners","product_shipping_class-domestic-package-up-to-2kg","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Stainless steel cleaner special - Muchenberger AG<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Stainless steel cleaner special - Muchenberger AG\" \/>\r\n<meta property=\"og:description\" content=\"Acidic stainless steel cleaner\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Muchenberger AG\" \/>\r\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/MuchenbergerBottmingen\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/024024_q.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"937\" \/>\r\n\t<meta property=\"og:image:height\" content=\"937\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/\",\"name\":\"Stainless steel cleaner special - Muchenberger AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Edelstahlreiniger-Spezial.jpg\",\"datePublished\":\"2021-11-28T22:32:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Edelstahlreiniger-Spezial.jpg\",\"contentUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Edelstahlreiniger-Spezial.jpg\",\"width\":1868,\"height\":1868,\"caption\":\"Edelstahlreiniger Spezial Flasche 1l\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/stainless-steel-cleaner-special\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stainless steel cleaner special\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/\",\"name\":\"Muchenberger AG\",\"description\":\"Sanit&auml;r Heizung Traumbad Pool\",\"publisher\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#organization\",\"name\":\"Muchenberger AG\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/logo_muchenberger.png\",\"contentUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/logo_muchenberger.png\",\"width\":372,\"height\":134,\"caption\":\"Muchenberger AG\"},\"image\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/MuchenbergerBottmingen\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stainless steel cleaner special - Muchenberger AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/","og_locale":"en_US","og_type":"article","og_title":"Stainless steel cleaner special - Muchenberger AG","og_description":"Acidic stainless steel cleaner","og_url":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/","og_site_name":"Muchenberger AG","article_publisher":"http:\/\/facebook.com\/MuchenbergerBottmingen","og_image":[{"width":937,"height":937,"url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/11\/024024_q.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/","url":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/","name":"Stainless steel cleaner special - Muchenberger AG","isPartOf":{"@id":"https:\/\/muchenberger.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/#primaryimage"},"image":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/#primaryimage"},"thumbnailUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2025\/03\/Edelstahlreiniger-Spezial.jpg","datePublished":"2021-11-28T22:32:31+00:00","breadcrumb":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/#primaryimage","url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2025\/03\/Edelstahlreiniger-Spezial.jpg","contentUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2025\/03\/Edelstahlreiniger-Spezial.jpg","width":1868,"height":1868,"caption":"Edelstahlreiniger Spezial Flasche 1l"},{"@type":"BreadcrumbList","@id":"https:\/\/muchenberger.ch\/en\/produkt\/stainless-steel-cleaner-special\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/muchenberger.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/muchenberger.ch\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Stainless steel cleaner special"}]},{"@type":"WebSite","@id":"https:\/\/muchenberger.ch\/en\/#website","url":"https:\/\/muchenberger.ch\/en\/","name":"Muchenberger AG","description":"Sanit&auml;r Heizung Traumbad Pool","publisher":{"@id":"https:\/\/muchenberger.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muchenberger.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/muchenberger.ch\/en\/#organization","name":"Muchenberger AG","url":"https:\/\/muchenberger.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/muchenberger.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2017\/11\/logo_muchenberger.png","contentUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2017\/11\/logo_muchenberger.png","width":372,"height":134,"caption":"Muchenberger AG"},"image":{"@id":"https:\/\/muchenberger.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/MuchenbergerBottmingen"]}]}},"_links":{"self":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/comments?post=2334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/media\/3217"}],"wp:attachment":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_brand?post=2334"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_cat?post=2334"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_tag?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}