{"id":2296,"date":"2021-12-04T14:32:05","date_gmt":"2021-12-04T13:32:05","guid":{"rendered":"https:\/\/muchenberger.ch\/produkt\/aco-only-for-swimming-pools\/"},"modified":"2021-12-04T14:32:05","modified_gmt":"2021-12-04T13:32:05","slug":"aco-only-for-swimming-baths","status":"publish","type":"product","link":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/","title":{"rendered":"ACO (only for swimming pools)"},"content":{"rendered":"<p class=\"p1\">ACO is an innovative, environmentally friendly product. ACO is suitable for all outdoor pools. ACO is characterized by 2 main features:<\/p>\n<ol>\n<li class=\"p1\">ACO enhances the natural sterilizing power of the sun: ACO multiplies the natural formation of free radicals by the sun.<\/li>\n<li class=\"p1\">ACO protects chlorine from photooxidation by the sun: the half-life of inorganic chlorine (40min) is increased by a factor of 4. This eliminates the need for stabilized chlorine or cyanuric acid.<\/li>\n<\/ol>\n<h2>Canister 5 liters<\/h2>\n<p><strong>Application \/ Dosage:<\/strong><br \/>\nAdd 1L\/100m3 pool contents weekly or 5L\/100m3 directly to the pool monthly. Shake product well before use.<\/p>\n<p><strong>Hazard statements:<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1613 \" src=\"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/12\/Screenshot-2022-04-21-171811.png\" alt=\"\" width=\"264\" height=\"149\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">AOC for swimming pools<\/p>\n","protected":false},"featured_media":2012,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[110,132],"product_tag":[],"class_list":["post-2296","product","type-product","status-publish","has-post-thumbnail","product_cat-all","product_cat-dryden-aqua-water-treatment-for-swimming-pools","product_shipping_class-domestic-package-up-to-10kg","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>ACO (only for swimming pools) - Muchenberger AG<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ACO (only for swimming pools) - Muchenberger AG\" \/>\r\n<meta property=\"og:description\" content=\"AOC for swimming pools\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Muchenberger AG\" \/>\r\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/MuchenbergerBottmingen\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/12\/ACO-5L-Kanister_24044_q.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2116\" \/>\r\n\t<meta property=\"og:image:height\" content=\"2116\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/\",\"name\":\"ACO (only for swimming pools) - Muchenberger AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ACO-5L-Kanister_24044_q.jpg\",\"datePublished\":\"2021-12-04T13:32:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ACO-5L-Kanister_24044_q.jpg\",\"contentUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ACO-5L-Kanister_24044_q.jpg\",\"width\":2116,\"height\":2116,\"caption\":\"Dryden Aqua ACO Kanister 5 Liter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/produkt\\\/aco-only-for-swimming-baths\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ACO (only for swimming pools)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/\",\"name\":\"Muchenberger AG\",\"description\":\"Sanit&auml;r Heizung Traumbad Pool\",\"publisher\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#organization\",\"name\":\"Muchenberger AG\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/logo_muchenberger.png\",\"contentUrl\":\"https:\\\/\\\/muchenberger.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/logo_muchenberger.png\",\"width\":372,\"height\":134,\"caption\":\"Muchenberger AG\"},\"image\":{\"@id\":\"https:\\\/\\\/muchenberger.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/MuchenbergerBottmingen\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACO (only for swimming pools) - Muchenberger AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/","og_locale":"en_US","og_type":"article","og_title":"ACO (only for swimming pools) - Muchenberger AG","og_description":"AOC for swimming pools","og_url":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/","og_site_name":"Muchenberger AG","article_publisher":"http:\/\/facebook.com\/MuchenbergerBottmingen","og_image":[{"width":2116,"height":2116,"url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/12\/ACO-5L-Kanister_24044_q.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/","url":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/","name":"ACO (only for swimming pools) - Muchenberger AG","isPartOf":{"@id":"https:\/\/muchenberger.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/#primaryimage"},"image":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/#primaryimage"},"thumbnailUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/12\/ACO-5L-Kanister_24044_q.jpg","datePublished":"2021-12-04T13:32:05+00:00","breadcrumb":{"@id":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/#primaryimage","url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/12\/ACO-5L-Kanister_24044_q.jpg","contentUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2021\/12\/ACO-5L-Kanister_24044_q.jpg","width":2116,"height":2116,"caption":"Dryden Aqua ACO Kanister 5 Liter"},{"@type":"BreadcrumbList","@id":"https:\/\/muchenberger.ch\/en\/produkt\/aco-only-for-swimming-baths\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/muchenberger.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/muchenberger.ch\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"ACO (only for swimming pools)"}]},{"@type":"WebSite","@id":"https:\/\/muchenberger.ch\/en\/#website","url":"https:\/\/muchenberger.ch\/en\/","name":"Muchenberger AG","description":"Sanit&auml;r Heizung Traumbad Pool","publisher":{"@id":"https:\/\/muchenberger.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muchenberger.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/muchenberger.ch\/en\/#organization","name":"Muchenberger AG","url":"https:\/\/muchenberger.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/muchenberger.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2017\/11\/logo_muchenberger.png","contentUrl":"https:\/\/muchenberger.ch\/wp-content\/uploads\/2017\/11\/logo_muchenberger.png","width":372,"height":134,"caption":"Muchenberger AG"},"image":{"@id":"https:\/\/muchenberger.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/MuchenbergerBottmingen"]}]}},"_links":{"self":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product\/2296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/comments?post=2296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/media\/2012"}],"wp:attachment":[{"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/media?parent=2296"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_brand?post=2296"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_cat?post=2296"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/muchenberger.ch\/en\/wp-json\/wp\/v2\/product_tag?post=2296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}